{"id":22777,"date":"2025-05-08T16:26:15","date_gmt":"2025-05-08T14:26:15","guid":{"rendered":"https:\/\/www.bvbs.de\/?p=22777"},"modified":"2025-05-08T16:37:33","modified_gmt":"2025-05-08T14:37:33","slug":"ddscad-und-metaroom","status":"publish","type":"post","link":"https:\/\/www.bvbs.de\/en\/2025\/05\/08\/ddscad-und-metaroom\/","title":{"rendered":"Naht\u00adlo\u00adses Zusam\u00admen\u00adspiel von digi\u00adta\u00adler Raum\u00ader\u00adfas\u00adsung und TGA-Planung"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;section&#8220; module_class=&#8220;font-roboto-hell&#8220; _builder_version=&#8220;4.27.3&#8243; custom_margin=&#8220;0px|||&#8220; custom_padding=&#8220;0px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row admin_label=&#8220;row&#8220; _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; custom_margin=&#8220;0px|||&#8220; custom_padding=&#8220;0px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.27.3&#8243; text_font_size=&#8220;15px&#8220; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; custom_padding=&#8220;||25px|&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h1 style=\"color: #696666;\">Nahtloses Zusammenspiel von digitaler Raumerfassung und TGA-Planung<\/h1>\n<p>&nbsp;<\/p>\n<p><strong>Ascheberg\/Puch bei Hallein, 08. Mai 2025 <\/strong>\u2013 Die Kombination aus der Raumscan-Plattform Metaroom und der Planungssoftware DDScad erm\u00f6glicht es TGA-Fachhandwerkern und \u2011planern jetzt, R\u00e4ume minutenschnell in 3D zu erfassen und auf dieser Grundlage umgehend mit der Planung der geb\u00e4udetechnischen Systeme zu starten. Hierf\u00fcr entwickelten die Softwareunternehmen Amrax und Graphisoft in Zusammenarbeit eine Schnittstelle, welche die reibungslose \u00dcbergabe der mit Metaroom erstellten 3D-Modelle an das gewerke\u00fcbergreifend einsetzbare TGA-Planungswerkzeug sicherstellt. So sparen die Anwender:innen viel Zeit und minimieren das Fehlerrisiko beim Anlegen von Geb\u00e4udegrundrissen und -modellen. Den Workflow und die vielf\u00e4ltigen Vorteile der neuen Softwarekombination stellen die Kooperationspartner am 21. Mai 2025 um 15 Uhr in einem kostenfreien Webinar vor.<\/p>\n<p>Das reibungslose Zusammenspiel der Anwendungen er\u00f6ffnet mehr Freiraum f\u00fcr die eigentliche Planungsarbeit. Mit der Metaroom Scan App erfassen TGA-Fachleute beliebige R\u00e4ume, Etagen oder Geb\u00e4ude mithilfe ihres Apple Pro-Mobilger\u00e4ts. Hieraus werden ma\u00dfstabsgetreue 2D-Grundrisse oder CAD-f\u00e4hige 3D-Modelle automatisiert erstellt. Anschlie\u00dfend k\u00f6nnen im Metaroom Workspace wichtige Bereiche und Elemente markiert oder mithilfe von KI im 3D-Modell erg\u00e4nzt werden. R\u00e4ume lassen sich definieren, und w\u00e4hrend des Scannens aufgenommene Schnappsch\u00fcsse von Raumbereichen k\u00f6nnen mit zus\u00e4tzlichen Informationen und Notizen angereichert werden. Gegen\u00fcber manuellen Messmethoden k\u00f6nnen mit Metaroom bis zu 90 Prozent Zeitersparnis erzielt werden.<\/p>\n<p>Die \u00dcbergabe der erfassten Geb\u00e4udeinformationen an DDScad erfolgt \u00fcber das offene Dateiformat IFC (Industry Foundation Classes). Auf der Basis des importierten 3D-Modells l\u00e4sst sich hier die komplette technische Geb\u00e4udeausr\u00fcstung projektieren \u2013 von der Elektrotechnik \u00fcber SHKL-Systeme bis hin zu sicherheitstechnischen Anlagen. Dabei unterst\u00fctzen vielf\u00e4ltige Fachfunktionen sowie integrierte automatische Berechnungs- und Pr\u00fcfroutinen. Dar\u00fcber hinaus bietet die OPEN-BIM-f\u00e4hige Planungssoftware leistungsstarke Visualisierungsoptionen f\u00fcr die hochwertige Pr\u00e4sentation von Planungsergebnissen sowie eine umfassende und rechtssichere Dokumentation.<\/p>\n<p>Im Rahmen des speziell auf TGA-Fachleute zugeschnittenen Webinars erl\u00e4utern die Referenten der beiden Unternehmen den gesamten Arbeitsprozess \u2013 vom Scan \u00fcber die Modellbearbeitung bis hin zum Import und zur Verwendung in der TGA-L\u00f6sung \u2013 anhand eines Praxisbeispiels. Dar\u00fcber hinaus erhalten die Teilnehmenden wertvolle Tipps f\u00fcr den Einsatz der Softwarekombination im Arbeitsalltag. Interessierte k\u00f6nnen sich hier registrieren. Dar\u00fcber hinaus wird das Webinar im Nachgang auf https:\/\/amrax.ai\/de\/webinare als On-Demand-Video verf\u00fcgbar sein.<\/p>\n<p>Weiterf\u00fchrende Informationen zu den Softwarel\u00f6sungen und Services von Amrax und Graphisoft: <a href=\"http:\/\/www.amrax.ai\/de\" target=\"_blank\" rel=\"noopener\">www.amrax.ai\/de<\/a> sowie <a href=\"http:\/\/www.graphisoft.de\" target=\"_blank\" rel=\"noopener\">www.graphisoft.de<\/a> und <a href=\"http:\/\/www.graphisoft.at\" target=\"_blank\" rel=\"noopener\">www.graphisoft.at<\/a>.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8220;https:\/\/www.bvbs.de\/wp-content\/uploads\/2025\/05\/Design-ohne-Titel-62.jpg&#8220; alt=&#8220;DDScad Amrax&#8220; title_text=&#8220;DDScad Amrax&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;center&#8220; align_last_edited=&#8220;on|desktop&#8220; disabled_on=&#8220;off|off|off&#8220; _builder_version=&#8220;4.27.3&#8243; max_width=&#8220;80%&#8220; custom_margin=&#8220;||0px|&#8220; custom_padding=&#8220;||10px|&#8220; hover_enabled=&#8220;0&#8243; always_center_on_mobile=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]&nbsp;[\/et_pb_image][et_pb_text _builder_version=&#8220;4.27.3&#8243; text_font_size=&#8220;15px&#8220; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; max_width=&#8220;80%&#8220; custom_padding=&#8220;||25px||false|false&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<div class=\"panel__text\">Das Zusammenspiel von DDScad und der Metaroom Scan App macht es m\u00f6glich, R\u00e4ume minutenschnell digital zu erfassen und direkt in dem TGA-Planungswerkzeug weiterzuplanen.<br \/>Foto \u00a9 Amrax\/Graphisoft<\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.3&#8243; text_font_size=&#8220;15px&#8220; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; max_width=&#8220;100%&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<p><strong>\u00dcber Metaroom by Amrax<\/strong><br \/>Amrax, das Unternehmen hinter Metaroom, spezialisiert sich auf KI-gest\u00fctzte 3D-Scanning-Technologien und bietet Unternehmen zug\u00e4ngliche Werkzeuge zur r\u00e4umlichen Digitalisierung. Das Flaggschiffprodukt Metaroom revolutioniert die Art und Weise, wie Geb\u00e4ude gescannt und modelliert werden, und erm\u00f6glicht eine intelligentere und besser vernetzte Welt. Die Anwendung verf\u00fcgt \u00fcber 20+ Exportformate u. a. \u00fcber optimierte Schnittstellen zu Archicad und DDScad. Mehr Informationen: www.amrax.ai\/de.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00dcber DDScad<\/strong><br \/>Die DDScad-Produktfamilie bietet Anwender:innen intelligente Werkzeuge f\u00fcr die Elektro- und SHKL-Planung, integrierte Berechnungen und umfassende M\u00f6glichkeiten zur Dokumentation aller Geb\u00e4udesysteme. Mit den BIM-Softwarel\u00f6sungen planen und realisieren Ingenieurs- und Handwerksbetriebe hochwertige TGA-Projekte zeit- und budgetgerecht. Alle DDScad-Produkte unterst\u00fctzen OPEN BIM. Das sorgt daf\u00fcr, dass Arbeitsabl\u00e4ufe transparent und erforderliche Daten jederzeit verf\u00fcgbar sind. Zudem sichert es die Langlebigkeit der gebauten Anlagen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00dcber Graphisoft<\/strong><br \/>Graphisoft\u00ae l\u00e4sst Teams gro\u00dfartige Architektur erschaffen. Dies wird m\u00f6glich durch preisgekr\u00f6nte Softwarel\u00f6sungen, Schulungsprogramme und professionelle Dienstleistungen f\u00fcr die AEC\/O-Branche. Archicad\u00ae ist die BIM-Software der Wahl f\u00fcr Architekt:innen und bietet einen vollst\u00e4ndigen, nahtlosen Entwurfs- und Dokumentationsworkflow f\u00fcr Architektur- und Bauingenieurb\u00fcros jeder Gr\u00f6\u00dfe. BIMx\u00ae, die beliebteste mobile und Web-BIM-App, erweitert die BIM-Erfahrung und schafft die Voraussetzungen daf\u00fcr, alle beteiligten Stellen in die Planung, die Realisierung und den Betriebslebenszyklus eines Geb\u00e4udes einzubeziehen. BIMcloud\u00ae, die erste und fortschrittlichste cloudbasierte Team-Kollaborationsl\u00f6sung der AEC\/O-Branche, erm\u00f6glicht die weltweite Zusammenarbeit in Echtzeit; unabh\u00e4ngig von der Gr\u00f6\u00dfe des Projekts und der Geschwindigkeit oder Qualit\u00e4t der Netzwerkverbindung der Teammitglieder. Graphisoft ist Teil der Nemetschek Group. Um mehr zu erfahren, besuchen Sie www.graphisoft.com.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Kom\u00adbi\u00adna\u00adti\u00adon aus der Raum\u00adscan-Platt\u00adform Meta\u00adroom und der Pla\u00adnungs\u00adsoft\u00adware DDScad erm\u00f6g\u00adlicht es TGA-Fach\u00adhand\u00adwer\u00adkern und \u2011pla\u00adnern jetzt, R\u00e4u\u00adme minu\u00adten\u00adschnell in 3D zu erfas\u00adsen und auf die\u00adser Grund\u00adla\u00adge umge\u00adhend mit der Planung&nbsp;\u2026&nbsp;<\/p>","protected":false},"author":760,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<strong>Bonn, im April 2024.<\/strong> Jeden Tag werden in Deutschland tausende von Baustellen mit zigtausenden Lieferscheinen im Papierformat beliefert. Die Erstellung, Weitergabe, Best\u00e4tigung gegen\u00fcber den Lieferanten, der Transport auf die Baustelle und die Aufbewahrung mit Pr\u00fcfung und regelkonformer Archivierung erfolgt mit hohem zeitlichen Aufwand. Zudem sind die Lieferscheine jeweils unterschiedlich aufgebaut. Auf Basis etablierter internationaler Standards zur Abbildung von Belegen zu Gesch\u00e4ftsvorf\u00e4llen schafft die Initiative \u201e1Lieferschein\u201c f\u00fcr eine geordnete Abwicklung von Lieferungen digitale Abhilfe. Das Programm f\u00fcr Aufma\u00df, Mengenermittlung und Abrechnung, MWM-Libero, \u00fcbernimmt die gesammelten Lieferschein-Informationen mit ihren Mengen und stellt diese zwecks Abrechnung dar. Das spart dem Abrechner jede Menge Zeit. Dar\u00fcber hinaus ist der Vorgang l\u00fcckenlos dokumentiert.\r\n\r\nF\u00fcr die kontinuierliche Lieferung der Baumaterialien fallen t\u00e4glich viele Lieferscheine an. Informationen wie Lieferscheinnummer, Fahrzeugnummer und Menge sind wichtig, \u00e4ndern sich aber je Lieferschein. Nun ist es m\u00f6glich, solche und weitere Informationen dem Empf\u00e4nger digital mit der 1Lieferschein-XML-Datei auf die Baustelle zu \u00fcbermitteln. Zwecks Weiterverarbeitung in MWM-Libero w\u00e4hlen die Anwendenden die auf dem Rechner gesammelten 1Lieferschein-XML-Dateien aus. MWM-Libero \u00fcbernimmt die in der zuvor selektierten LV-Position relevanten Elemente und stellt diese dar. Da das Programm \u00fcber die Generierung von Kriterien-Informationen verf\u00fcgt, k\u00f6nnen die f\u00fcr die Abrechnung ben\u00f6tigen Lieferschein-Informationen angepasst werden. Weiterhin steht f\u00fcr die Umrechnung der Lieferschein-Mengeneinheit zur LV-Mengeneinheit ein Umrechnungsfaktor zu Verf\u00fcgung. Diese Vorgehensweise stellt eine l\u00fcckenlose Dokumentation der gelieferten Mengen in der Bauabrechnung sicher.\r\n\r\nF\u00fcr die Betrachtung von 1Lieferschein-XML-Dateien stellt der MWM-Partner anouri auf seiner Plattform gaeb-365.online (https:\/\/mein.gaeb-365.online) einen kostenlosen Viewer zur Verf\u00fcgung.\r\n\r\nWeitere Informationen www.mwm.de und www.1lieferschein.com\r\n\r\nWeitere Informationen <a href=\"http:\/\/www.mwm.de\" target=\"_blank\" rel=\"noopener\">www.mwm.de<\/a>, <a href=\"http:\/\/www.anouri.gmbh\" target=\"_blank\" rel=\"noopener\">www.anouri.gmbh <\/a> und <a href=\"http:\/\/www.emidat.com\" target=\"_blank\" rel=\"noopener\">www.emidat.com<\/a>\r\n\r\nMWM ist auf der digitalBAU in K\u00f6ln in Halle 1, Stand 308 (BVSB-Stand) vertreten.\r\n\r\n\u00a0\r\n\r\n[caption id=\"attachment_13339\" align=\"alignnone\" width=\"1024\"]<img class=\"wp-image-13339 size-large\" src=\"https:\/\/www.bvbs.de\/wp-content\/uploads\/2024\/04\/Lieferschein-Muster-Asphalt-MWM-1024x468.jpg\" alt=\"\" width=\"1024\" height=\"468\" \/> Beispielhafter Asphalt-Lieferschein in MWM-Libero[\/caption]\r\n\r\n\u00a0\r\n\r\n[caption id=\"attachment_13341\" align=\"alignnone\" width=\"1024\"]<img class=\"wp-image-13341 size-large\" src=\"https:\/\/www.bvbs.de\/wp-content\/uploads\/2024\/04\/MWM-Libero-Abrechnung-Asphalt-aus-Lieferschein-1024x355.jpg\" alt=\"\" width=\"1024\" height=\"355\" \/> In MWM-Libero erstellte Abrechnung auf Basis des elektronischen Lieferscheins[\/caption]\r\n\r\n\u00a0\r\n\r\n[caption id=\"attachment_13340\" align=\"alignnone\" width=\"1024\"]<img class=\"wp-image-13340 size-large\" src=\"https:\/\/www.bvbs.de\/wp-content\/uploads\/2024\/04\/Lieferschein-Muster-Beton-MWM-1024x436.jpg\" alt=\"\" width=\"1024\" height=\"436\" \/> Beispielhafter Beton-Lieferschein in MWM-Libero[\/caption]\r\n\r\n\u00a0\r\n\r\n[caption id=\"attachment_10578\" align=\"alignnone\" width=\"836\"]<img class=\"wp-image-10578 size-full\" src=\"https:\/\/www.bvbs.de\/wp-content\/uploads\/2023\/11\/XRechnung_MWM-Viewer_mit_X31.jpg\" alt=\"\" width=\"836\" height=\"812\" \/> XRechnung im MWM-Viewer[\/caption]\r\n\r\n\u00a0\r\n\r\nQuelle aller Bilder:\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 MWM Software & Beratung GmbH, Bonn\r\n\r\n\u00a0\r\n\r\n<strong>\u00dcber MWM<\/strong>\r\n\r\nIm Juli 1992 gr\u00fcndeten Dipl.-Ing. (FH) Michael Hocks und Dipl.-Ing. Wilhelm Veenhuis die MWM Software & Beratung GmbH mit dem Ziel, Dienstleistungen und EDV-L\u00f6sungen f\u00fcr branchenspezi\u00adfische IT-Fragestellungen im Bauwesen anzubieten. 2021 stieg Dipl.-Ing. (FH) Stefan Berensmann in das Unternehmen ein. \u00dcber 3.600 Kunden mit \u00fcber 26.000 Installationen beweisen den Erfolg des Unternehmens. So bietet MWM Interessierten unter anderem das GAEB-Konvertierungstool MWM-Primo, MWM-Libero f\u00fcr Aufma\u00df, freie sowie REB-Mengenermittlung und Bauabrechnung, XRechnung, Aufma\u00df 365 f\u00fcr beliebige Endger\u00e4te (Browser-L\u00f6sung), MWM-Pisa f\u00fcr die Angebots\u00adbearbeitung, MWM-Rialto f\u00fcr die Umwandlung von GAEB- in Excel-Dateien und den DA11-Konverter MWM-Ponto etc.\r\n\r\nSeit dem Jahr 2000 ist MWM Mitglied im Bundesverband Software und Digitalisierung im Bauwesen e.V.. Seit 2001 ist Wilhelm Veenhuis im Vorstand des BVBS und seit 2006 leitet er den Arbeitskreis \u201eDatenaustausch\u201c. Seit 2017 ist MWM F\u00f6rdermitglied im Bundesverband Aufma\u00dftechnik e.V.\r\n\r\n.","_et_gb_content_width":"","wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-22777","post","type-post","status-publish","format-standard","hentry","category-graphisoft"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Nahtloses Zusammenspiel von digitaler Raumerfassung und TGA-Planung - BVBS Bundesverband Software und Digitalisierung im Bauwesen e.V.<\/title>\r\n<meta name=\"description\" content=\"Nahtloses Zusammenspiel von digitaler Raumerfassung und TGA-Planung durch dei Raumscan-Plattform Metaroom und die Planungssoftware DDScad\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.bvbs.de\/en\/2025\/05\/08\/ddscad-und-metaroom\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_GB\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Nahtloses Zusammenspiel von digitaler Raumerfassung und TGA-Planung - BVBS Bundesverband Software und Digitalisierung im Bauwesen e.V.\" \/>\r\n<meta property=\"og:description\" content=\"Nahtloses Zusammenspiel von digitaler Raumerfassung und TGA-Planung durch dei Raumscan-Plattform Metaroom und die Planungssoftware DDScad\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.bvbs.de\/en\/2025\/05\/08\/ddscad-und-metaroom\/\" \/>\r\n<meta property=\"og:site_name\" content=\"BVBS Bundesverband Software und Digitalisierung im Bauwesen e.V.\" \/>\r\n<meta property=\"article:published_time\" content=\"2025-05-08T14:26:15+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-05-08T14:37:33+00:00\" \/>\r\n<meta name=\"author\" content=\"Daniel Waltermann\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Waltermann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.bvbs.de\/2025\/05\/08\/ddscad-und-metaroom\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.bvbs.de\/2025\/05\/08\/ddscad-und-metaroom\/\"},\"author\":{\"name\":\"Daniel Waltermann\",\"@id\":\"https:\/\/www.bvbs.de\/#\/schema\/person\/13f757c48b8e4cb7d02ed99e680513af\"},\"headline\":\"Nahtloses Zusammenspiel von digitaler Raumerfassung und TGA-Planung\",\"datePublished\":\"2025-05-08T14:26:15+00:00\",\"dateModified\":\"2025-05-08T14:37:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.bvbs.de\/2025\/05\/08\/ddscad-und-metaroom\/\"},\"wordCount\":953,\"publisher\":{\"@id\":\"https:\/\/www.bvbs.de\/#organization\"},\"articleSection\":[\"GRAPHISOFT\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bvbs.de\/2025\/05\/08\/ddscad-und-metaroom\/\",\"url\":\"https:\/\/www.bvbs.de\/2025\/05\/08\/ddscad-und-metaroom\/\",\"name\":\"Nahtloses Zusammenspiel von digitaler Raumerfassung und TGA-Planung - BVBS Bundesverband Software und Digitalisierung im Bauwesen e.V.\",\"isPartOf\":{\"@id\":\"https:\/\/www.bvbs.de\/#website\"},\"datePublished\":\"2025-05-08T14:26:15+00:00\",\"dateModified\":\"2025-05-08T14:37:33+00:00\",\"description\":\"Nahtloses Zusammenspiel von digitaler Raumerfassung und TGA-Planung durch dei Raumscan-Plattform Metaroom und die Planungssoftware DDScad\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bvbs.de\/2025\/05\/08\/ddscad-und-metaroom\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bvbs.de\/2025\/05\/08\/ddscad-und-metaroom\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bvbs.de\/2025\/05\/08\/ddscad-und-metaroom\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.bvbs.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nahtloses Zusammenspiel von digitaler Raumerfassung und TGA-Planung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bvbs.de\/#website\",\"url\":\"https:\/\/www.bvbs.de\/\",\"name\":\"BVBS Bundesverband Software und Digitalisierung im Bauwesen e.V.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.bvbs.de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bvbs.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bvbs.de\/#organization\",\"name\":\"BVBS Bundesverband Software und Digitalisierung im Bauwesen\",\"url\":\"https:\/\/www.bvbs.de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.bvbs.de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bvbs.de\/wp-content\/uploads\/2024\/01\/cropped-favicon-bvbs.png\",\"contentUrl\":\"https:\/\/www.bvbs.de\/wp-content\/uploads\/2024\/01\/cropped-favicon-bvbs.png\",\"width\":512,\"height\":512,\"caption\":\"BVBS Bundesverband Software und Digitalisierung im Bauwesen\"},\"image\":{\"@id\":\"https:\/\/www.bvbs.de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bvbs.de\/#\/schema\/person\/13f757c48b8e4cb7d02ed99e680513af\",\"name\":\"Daniel Waltermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.bvbs.de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4e2de84447cc0a28f5efb60ba582f217?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4e2de84447cc0a28f5efb60ba582f217?s=96&d=mm&r=g\",\"caption\":\"Daniel Waltermann\"},\"url\":\"https:\/\/www.bvbs.de\/en\/author\/dwaltermann\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Naht\u00adlo\u00adses Zusam\u00admen\u00adspiel von digi\u00adta\u00adler Raum\u00ader\u00adfas\u00adsung und TGA-Pla\u00adnung \u2014 BVBS Bun\u00addes\u00adver\u00adband Soft\u00adware und Digi\u00adta\u00adli\u00adsie\u00adrung im Bau\u00adwe\u00adsen e.V.","description":"Naht\u00adlo\u00adses Zusam\u00admen\u00adspiel von digi\u00adta\u00adler Raum\u00ader\u00adfas\u00adsung und TGA-Pla\u00adnung durch dei Raum\u00adscan-Platt\u00adform Meta\u00adroom und die Pla\u00adnungs\u00adsoft\u00adware DDScad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bvbs.de\/en\/2025\/05\/08\/ddscad-und-metaroom\/","og_locale":"en_GB","og_type":"article","og_title":"Nahtloses Zusammenspiel von digitaler Raumerfassung und TGA-Planung - BVBS Bundesverband Software und Digitalisierung im Bauwesen e.V.","og_description":"Nahtloses Zusammenspiel von digitaler Raumerfassung und TGA-Planung durch dei Raumscan-Plattform Metaroom und die Planungssoftware DDScad","og_url":"https:\/\/www.bvbs.de\/en\/2025\/05\/08\/ddscad-und-metaroom\/","og_site_name":"BVBS Bundesverband Software und Digitalisierung im Bauwesen e.V.","article_published_time":"2025-05-08T14:26:15+00:00","article_modified_time":"2025-05-08T14:37:33+00:00","author":"Daniel Waltermann","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniel Waltermann","Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bvbs.de\/2025\/05\/08\/ddscad-und-metaroom\/#article","isPartOf":{"@id":"https:\/\/www.bvbs.de\/2025\/05\/08\/ddscad-und-metaroom\/"},"author":{"name":"Daniel Waltermann","@id":"https:\/\/www.bvbs.de\/#\/schema\/person\/13f757c48b8e4cb7d02ed99e680513af"},"headline":"Nahtloses Zusammenspiel von digitaler Raumerfassung und TGA-Planung","datePublished":"2025-05-08T14:26:15+00:00","dateModified":"2025-05-08T14:37:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bvbs.de\/2025\/05\/08\/ddscad-und-metaroom\/"},"wordCount":953,"publisher":{"@id":"https:\/\/www.bvbs.de\/#organization"},"articleSection":["GRAPHISOFT"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.bvbs.de\/2025\/05\/08\/ddscad-und-metaroom\/","url":"https:\/\/www.bvbs.de\/2025\/05\/08\/ddscad-und-metaroom\/","name":"Naht\u00adlo\u00adses Zusam\u00admen\u00adspiel von digi\u00adta\u00adler Raum\u00ader\u00adfas\u00adsung und TGA-Pla\u00adnung \u2014 BVBS Bun\u00addes\u00adver\u00adband Soft\u00adware und Digi\u00adta\u00adli\u00adsie\u00adrung im Bau\u00adwe\u00adsen e.V.","isPartOf":{"@id":"https:\/\/www.bvbs.de\/#website"},"datePublished":"2025-05-08T14:26:15+00:00","dateModified":"2025-05-08T14:37:33+00:00","description":"Naht\u00adlo\u00adses Zusam\u00admen\u00adspiel von digi\u00adta\u00adler Raum\u00ader\u00adfas\u00adsung und TGA-Pla\u00adnung durch dei Raum\u00adscan-Platt\u00adform Meta\u00adroom und die Pla\u00adnungs\u00adsoft\u00adware DDScad","breadcrumb":{"@id":"https:\/\/www.bvbs.de\/2025\/05\/08\/ddscad-und-metaroom\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bvbs.de\/2025\/05\/08\/ddscad-und-metaroom\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bvbs.de\/2025\/05\/08\/ddscad-und-metaroom\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.bvbs.de\/"},{"@type":"ListItem","position":2,"name":"Nahtloses Zusammenspiel von digitaler Raumerfassung und TGA-Planung"}]},{"@type":"WebSite","@id":"https:\/\/www.bvbs.de\/#website","url":"https:\/\/www.bvbs.de\/","name":"BVBS Bun\u00addes\u00adver\u00adband Soft\u00adware und Digi\u00adta\u00adli\u00adsie\u00adrung im Bau\u00adwe\u00adsen e.V.","description":"","publisher":{"@id":"https:\/\/www.bvbs.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bvbs.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.bvbs.de\/#organization","name":"BVBS Bun\u00addes\u00adver\u00adband Soft\u00adware und Digi\u00adta\u00adli\u00adsie\u00adrung im Bauwesen","url":"https:\/\/www.bvbs.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.bvbs.de\/#\/schema\/logo\/image\/","url":"https:\/\/www.bvbs.de\/wp-content\/uploads\/2024\/01\/cropped-favicon-bvbs.png","contentUrl":"https:\/\/www.bvbs.de\/wp-content\/uploads\/2024\/01\/cropped-favicon-bvbs.png","width":512,"height":512,"caption":"BVBS Bundesverband Software und Digitalisierung im Bauwesen"},"image":{"@id":"https:\/\/www.bvbs.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.bvbs.de\/#\/schema\/person\/13f757c48b8e4cb7d02ed99e680513af","name":"Dani\u00adel Waltermann","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.bvbs.de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4e2de84447cc0a28f5efb60ba582f217?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4e2de84447cc0a28f5efb60ba582f217?s=96&d=mm&r=g","caption":"Daniel Waltermann"},"url":"https:\/\/www.bvbs.de\/en\/author\/dwaltermann\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bvbs.de\/en\/wp-json\/wp\/v2\/posts\/22777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bvbs.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bvbs.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bvbs.de\/en\/wp-json\/wp\/v2\/users\/760"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bvbs.de\/en\/wp-json\/wp\/v2\/comments?post=22777"}],"version-history":[{"count":0,"href":"https:\/\/www.bvbs.de\/en\/wp-json\/wp\/v2\/posts\/22777\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bvbs.de\/en\/wp-json\/wp\/v2\/media?parent=22777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bvbs.de\/en\/wp-json\/wp\/v2\/categories?post=22777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bvbs.de\/en\/wp-json\/wp\/v2\/tags?post=22777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}